{"id":1821,"count":1,"description":"","link":"https:\/\/ad-doge.com\/blog\/tag\/litecoin-whale-deposit\/","name":"Litecoin Whale Deposit","slug":"litecoin-whale-deposit","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/tags\/1821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/posts?tags=1821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}