{"id":2755,"count":1,"description":"","link":"https:\/\/ad-doge.com\/blog\/tag\/eric-conner\/","name":"Eric Conner","slug":"eric-conner","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/tags\/2755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/posts?tags=2755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}