{"id":3132,"count":1,"description":"","link":"https:\/\/ad-doge.com\/blog\/tag\/xrp-dip\/","name":"XRP Dip","slug":"xrp-dip","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/tags\/3132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ad-doge.com\/blog\/wp-json\/wp\/v2\/posts?tags=3132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}